{"id":590,"date":"2013-07-16T13:33:04","date_gmt":"2013-07-16T11:33:04","guid":{"rendered":"http:\/\/www.twenta.nl\/\/?page_id=590"},"modified":"2016-02-12T13:25:41","modified_gmt":"2016-02-12T12:25:41","slug":"590-2","status":"publish","type":"page","link":"https:\/\/www.twenta.nl\/fr\/produkten-2\/bodentreppen-aluminium\/590-2\/","title":{"rendered":"(Deutschland) Typ 2410 f\u00fcr den Zugang zu Aufzug-Maschinenr\u00e4umen"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-fr\">D\u00e9sol\u00e9, cet article est seulement disponible en <a href=\"https:\/\/www.twenta.nl\/de\/wp-json\/wp\/v2\/pages\/590\" class=\"qtranxs-available-language-link qtranxs-available-language-link-de\" title=\"Deutschland\">Deutschland<\/a> et <a href=\"https:\/\/www.twenta.nl\/be\/wp-json\/wp\/v2\/pages\/590\" class=\"qtranxs-available-language-link qtranxs-available-language-link-be\" title=\"Belgi\u00eb\">Belgi\u00eb<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>D\u00e9sol\u00e9, cet article est seulement disponible en Deutschland et Belgi\u00eb.<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":374,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-590","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"DIN EN 14975 : 2010-12 U-Wert : 1,1 W\/m2K Maximale Belastung : 175 kg Luftdichtheitsklasse : Klasse 4 Wie Typ 2400, jedoch f\u00fcr den Zugang zu Aufzug-Maschinenr\u00e4umen entwickelt. Die Treppe wird standardm\u00e4\u00dfig in gr\u00f6\u00dferen Abmessungen gefertigt, sodass Kundendiensttechniker den Aufzug-Maschinenraum auf eine sichere Weise erreichen k\u00f6nnen. Standardm\u00e4\u00dfig werden ein Gel\u00e4nder und ein Treppe-Verriegelung angebracht, sodass die Treppe\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.twenta.nl\/fr\/produkten-2\/bodentreppen-aluminium\/590-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Twenta BV | bodentreppen, loftladders, vlieringtrappen, zoldertrappen, kniestockt\u00fcren\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"(Deutschland) Typ 2410 f\u00fcr den Zugang zu Aufzug-Maschinenr\u00e4umen | Twenta BV\" \/>\n\t\t<meta property=\"og:description\" content=\"DIN EN 14975 : 2010-12 U-Wert : 1,1 W\/m2K Maximale Belastung : 175 kg Luftdichtheitsklasse : Klasse 4 Wie Typ 2400, jedoch f\u00fcr den Zugang zu Aufzug-Maschinenr\u00e4umen entwickelt. Die Treppe wird standardm\u00e4\u00dfig in gr\u00f6\u00dferen Abmessungen gefertigt, sodass Kundendiensttechniker den Aufzug-Maschinenraum auf eine sichere Weise erreichen k\u00f6nnen. Standardm\u00e4\u00dfig werden ein Gel\u00e4nder und ein Treppe-Verriegelung angebracht, sodass die Treppe\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.twenta.nl\/fr\/produkten-2\/bodentreppen-aluminium\/590-2\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-07-16T11:33:04+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-02-12T12:25:41+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"(Deutschland) Typ 2410 f\u00fcr den Zugang zu Aufzug-Maschinenr\u00e4umen | Twenta BV\" \/>\n\t\t<meta name=\"twitter:description\" content=\"DIN EN 14975 : 2010-12 U-Wert : 1,1 W\/m2K Maximale Belastung : 175 kg Luftdichtheitsklasse : Klasse 4 Wie Typ 2400, jedoch f\u00fcr den Zugang zu Aufzug-Maschinenr\u00e4umen entwickelt. Die Treppe wird standardm\u00e4\u00dfig in gr\u00f6\u00dferen Abmessungen gefertigt, sodass Kundendiensttechniker den Aufzug-Maschinenraum auf eine sichere Weise erreichen k\u00f6nnen. Standardm\u00e4\u00dfig werden ein Gel\u00e4nder und ein Treppe-Verriegelung angebracht, sodass die Treppe\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/fr\\\/produkten-2\\\/bodentreppen-aluminium\\\/590-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/fr#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.twenta.nl\\\/fr\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/fr\\\/produkten-2\\\/#listItem\",\"name\":\"(Deutschland) Produkte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/fr\\\/produkten-2\\\/#listItem\",\"position\":2,\"name\":\"(Deutschland) Produkte\",\"item\":\"https:\\\/\\\/www.twenta.nl\\\/fr\\\/produkten-2\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/fr\\\/produkten-2\\\/bodentreppen-aluminium\\\/#listItem\",\"name\":\"(Deutschland) Scherentreppen aus Aluminium\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/fr#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/fr\\\/produkten-2\\\/bodentreppen-aluminium\\\/#listItem\",\"position\":3,\"name\":\"(Deutschland) Scherentreppen aus Aluminium\",\"item\":\"https:\\\/\\\/www.twenta.nl\\\/fr\\\/produkten-2\\\/bodentreppen-aluminium\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/fr\\\/produkten-2\\\/bodentreppen-aluminium\\\/590-2\\\/#listItem\",\"name\":\"(Deutschland) Typ 2410 f\\u00fcr den Zugang zu Aufzug-Maschinenr\\u00e4umen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/fr\\\/produkten-2\\\/#listItem\",\"name\":\"(Deutschland) Produkte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/fr\\\/produkten-2\\\/bodentreppen-aluminium\\\/590-2\\\/#listItem\",\"position\":4,\"name\":\"(Deutschland) Typ 2410 f\\u00fcr den Zugang zu Aufzug-Maschinenr\\u00e4umen\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/fr\\\/produkten-2\\\/bodentreppen-aluminium\\\/#listItem\",\"name\":\"(Deutschland) Scherentreppen aus Aluminium\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/fr\\\/#person\",\"name\":\"Danny\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/fr\\\/produkten-2\\\/bodentreppen-aluminium\\\/590-2\\\/#webpage\",\"url\":\"https:\\\/\\\/www.twenta.nl\\\/fr\\\/produkten-2\\\/bodentreppen-aluminium\\\/590-2\\\/\",\"name\":\"(Deutschland) Typ 2410 f\\u00fcr den Zugang zu Aufzug-Maschinenr\\u00e4umen | Twenta BV\",\"description\":\"DIN EN 14975 : 2010-12 U-Wert : 1,1 W\\\/m2K Maximale Belastung : 175 kg Luftdichtheitsklasse : Klasse 4 Wie Typ 2400, jedoch f\\u00fcr den Zugang zu Aufzug-Maschinenr\\u00e4umen entwickelt. Die Treppe wird standardm\\u00e4\\u00dfig in gr\\u00f6\\u00dferen Abmessungen gefertigt, sodass Kundendiensttechniker den Aufzug-Maschinenraum auf eine sichere Weise erreichen k\\u00f6nnen. Standardm\\u00e4\\u00dfig werden ein Gel\\u00e4nder und ein Treppe-Verriegelung angebracht, sodass die Treppe\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/fr\\\/produkten-2\\\/bodentreppen-aluminium\\\/590-2\\\/#breadcrumblist\"},\"datePublished\":\"2013-07-16T13:33:04+02:00\",\"dateModified\":\"2016-02-12T13:25:41+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.twenta.nl\\\/fr\\\/\",\"name\":\"Twenta BV\",\"description\":\"bodentreppen, loftladders, vlieringtrappen, zoldertrappen, kniestockt\\u00fcren\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/fr\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"(Deutschland) Typ 2410 f\u00fcr den Zugang zu Aufzug-Maschinenr\u00e4umen | Twenta BV","description":"DIN EN 14975 : 2010-12 U-Wert : 1,1 W\/m2K Maximale Belastung : 175 kg Luftdichtheitsklasse : Klasse 4 Wie Typ 2400, jedoch f\u00fcr den Zugang zu Aufzug-Maschinenr\u00e4umen entwickelt. Die Treppe wird standardm\u00e4\u00dfig in gr\u00f6\u00dferen Abmessungen gefertigt, sodass Kundendiensttechniker den Aufzug-Maschinenraum auf eine sichere Weise erreichen k\u00f6nnen. Standardm\u00e4\u00dfig werden ein Gel\u00e4nder und ein Treppe-Verriegelung angebracht, sodass die Treppe","canonical_url":"https:\/\/www.twenta.nl\/fr\/produkten-2\/bodentreppen-aluminium\/590-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.twenta.nl\/fr\/produkten-2\/bodentreppen-aluminium\/590-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.twenta.nl\/fr#listItem","position":1,"name":"Home","item":"https:\/\/www.twenta.nl\/fr","nextItem":{"@type":"ListItem","@id":"https:\/\/www.twenta.nl\/fr\/produkten-2\/#listItem","name":"(Deutschland) Produkte"}},{"@type":"ListItem","@id":"https:\/\/www.twenta.nl\/fr\/produkten-2\/#listItem","position":2,"name":"(Deutschland) Produkte","item":"https:\/\/www.twenta.nl\/fr\/produkten-2\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.twenta.nl\/fr\/produkten-2\/bodentreppen-aluminium\/#listItem","name":"(Deutschland) Scherentreppen aus Aluminium"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.twenta.nl\/fr#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.twenta.nl\/fr\/produkten-2\/bodentreppen-aluminium\/#listItem","position":3,"name":"(Deutschland) Scherentreppen aus Aluminium","item":"https:\/\/www.twenta.nl\/fr\/produkten-2\/bodentreppen-aluminium\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.twenta.nl\/fr\/produkten-2\/bodentreppen-aluminium\/590-2\/#listItem","name":"(Deutschland) Typ 2410 f\u00fcr den Zugang zu Aufzug-Maschinenr\u00e4umen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.twenta.nl\/fr\/produkten-2\/#listItem","name":"(Deutschland) Produkte"}},{"@type":"ListItem","@id":"https:\/\/www.twenta.nl\/fr\/produkten-2\/bodentreppen-aluminium\/590-2\/#listItem","position":4,"name":"(Deutschland) Typ 2410 f\u00fcr den Zugang zu Aufzug-Maschinenr\u00e4umen","previousItem":{"@type":"ListItem","@id":"https:\/\/www.twenta.nl\/fr\/produkten-2\/bodentreppen-aluminium\/#listItem","name":"(Deutschland) Scherentreppen aus Aluminium"}}]},{"@type":"Person","@id":"https:\/\/www.twenta.nl\/fr\/#person","name":"Danny"},{"@type":"WebPage","@id":"https:\/\/www.twenta.nl\/fr\/produkten-2\/bodentreppen-aluminium\/590-2\/#webpage","url":"https:\/\/www.twenta.nl\/fr\/produkten-2\/bodentreppen-aluminium\/590-2\/","name":"(Deutschland) Typ 2410 f\u00fcr den Zugang zu Aufzug-Maschinenr\u00e4umen | Twenta BV","description":"DIN EN 14975 : 2010-12 U-Wert : 1,1 W\/m2K Maximale Belastung : 175 kg Luftdichtheitsklasse : Klasse 4 Wie Typ 2400, jedoch f\u00fcr den Zugang zu Aufzug-Maschinenr\u00e4umen entwickelt. Die Treppe wird standardm\u00e4\u00dfig in gr\u00f6\u00dferen Abmessungen gefertigt, sodass Kundendiensttechniker den Aufzug-Maschinenraum auf eine sichere Weise erreichen k\u00f6nnen. Standardm\u00e4\u00dfig werden ein Gel\u00e4nder und ein Treppe-Verriegelung angebracht, sodass die Treppe","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/www.twenta.nl\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/www.twenta.nl\/fr\/produkten-2\/bodentreppen-aluminium\/590-2\/#breadcrumblist"},"datePublished":"2013-07-16T13:33:04+02:00","dateModified":"2016-02-12T13:25:41+01:00"},{"@type":"WebSite","@id":"https:\/\/www.twenta.nl\/fr\/#website","url":"https:\/\/www.twenta.nl\/fr\/","name":"Twenta BV","description":"bodentreppen, loftladders, vlieringtrappen, zoldertrappen, kniestockt\u00fcren","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/www.twenta.nl\/fr\/#person"}}]},"og:locale":"fr_FR","og:site_name":"Twenta BV | bodentreppen, loftladders, vlieringtrappen, zoldertrappen, kniestockt\u00fcren","og:type":"article","og:title":"(Deutschland) Typ 2410 f\u00fcr den Zugang zu Aufzug-Maschinenr\u00e4umen | Twenta BV","og:description":"DIN EN 14975 : 2010-12 U-Wert : 1,1 W\/m2K Maximale Belastung : 175 kg Luftdichtheitsklasse : Klasse 4 Wie Typ 2400, jedoch f\u00fcr den Zugang zu Aufzug-Maschinenr\u00e4umen entwickelt. Die Treppe wird standardm\u00e4\u00dfig in gr\u00f6\u00dferen Abmessungen gefertigt, sodass Kundendiensttechniker den Aufzug-Maschinenraum auf eine sichere Weise erreichen k\u00f6nnen. Standardm\u00e4\u00dfig werden ein Gel\u00e4nder und ein Treppe-Verriegelung angebracht, sodass die Treppe","og:url":"https:\/\/www.twenta.nl\/fr\/produkten-2\/bodentreppen-aluminium\/590-2\/","article:published_time":"2013-07-16T11:33:04+00:00","article:modified_time":"2016-02-12T12:25:41+00:00","twitter:card":"summary","twitter:title":"(Deutschland) Typ 2410 f\u00fcr den Zugang zu Aufzug-Maschinenr\u00e4umen | Twenta BV","twitter:description":"DIN EN 14975 : 2010-12 U-Wert : 1,1 W\/m2K Maximale Belastung : 175 kg Luftdichtheitsklasse : Klasse 4 Wie Typ 2400, jedoch f\u00fcr den Zugang zu Aufzug-Maschinenr\u00e4umen entwickelt. Die Treppe wird standardm\u00e4\u00dfig in gr\u00f6\u00dferen Abmessungen gefertigt, sodass Kundendiensttechniker den Aufzug-Maschinenraum auf eine sichere Weise erreichen k\u00f6nnen. Standardm\u00e4\u00dfig werden ein Gel\u00e4nder und ein Treppe-Verriegelung angebracht, sodass die Treppe"},"aioseo_meta_data":{"post_id":"590","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-04 15:53:34","updated":"2025-07-15 12:55:43","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/www.twenta.nl\/fr\/wp-json\/wp\/v2\/pages\/590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.twenta.nl\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.twenta.nl\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.twenta.nl\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.twenta.nl\/fr\/wp-json\/wp\/v2\/comments?post=590"}],"version-history":[{"count":1,"href":"https:\/\/www.twenta.nl\/fr\/wp-json\/wp\/v2\/pages\/590\/revisions"}],"predecessor-version":[{"id":591,"href":"https:\/\/www.twenta.nl\/fr\/wp-json\/wp\/v2\/pages\/590\/revisions\/591"}],"up":[{"embeddable":true,"href":"https:\/\/www.twenta.nl\/fr\/wp-json\/wp\/v2\/pages\/374"}],"wp:attachment":[{"href":"https:\/\/www.twenta.nl\/fr\/wp-json\/wp\/v2\/media?parent=590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}