{"id":381,"date":"2012-06-03T12:23:03","date_gmt":"2012-06-03T10:23:03","guid":{"rendered":"http:\/\/www.twenta.nl\/\/?page_id=381"},"modified":"2015-07-19T12:07:06","modified_gmt":"2015-07-19T10:07:06","slug":"gegoten-aluminium-type-2400-d","status":"publish","type":"page","link":"https:\/\/www.twenta.nl\/be\/produkten-2\/bodentreppen-aluminium\/gegoten-aluminium-type-2400-d\/","title":{"rendered":"Type 2400, gegoten aluminium schaartrap"},"content":{"rendered":"<p><\/p>\n<ul>\n<li><a href=\"http:\/\/www.twenta.nl\/\/wp-content\/uploads\/VT_2400_V01.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-623\" src=\"http:\/\/www.twenta.nl\/\/wp-content\/uploads\/VT_2400_V01-145x300.jpg\" alt=\"VT_2400_V01\" width=\"145\" height=\"300\" srcset=\"https:\/\/www.twenta.nl\/wp-content\/uploads\/VT_2400_V01-145x300.jpg 145w, https:\/\/www.twenta.nl\/wp-content\/uploads\/VT_2400_V01-496x1024.jpg 496w, https:\/\/www.twenta.nl\/wp-content\/uploads\/VT_2400_V01.jpg 582w\" sizes=\"auto, (max-width: 145px) 100vw, 145px\" \/><\/a><strong>DIN EN 14975 : 2010-12<\/strong><\/li>\n<li><strong>k-waarde : 1,1\u00a0W\/m2K<\/strong><\/li>\n<li><strong>Maximale belasting : 175 kg<\/strong><\/li>\n<li><strong>Luchtdichtheidsklasse : klasse 4<\/strong><\/li>\n<\/ul>\n<p>Type 2400 is het summum van de vlieringtrappen, speciaal bij frequent gebruik en plafondhoogtes boven 280 cm. Vervaardigd uit zware gegoten aluminium profielen en gepolijste treden van 14 cm diep. Geleverd met multiplex raveelbak waarin het ge\u00efsoleerde luik van 56 mm \u00a0(U=1,1 W\/m2K)\u00a0is afgehangen. Bediening met trekstok en kunststof treksluiting. Balancering van het luik door een systeem van verstelbare zij-armen en veren. Balancering van de trap door een systeem van looprails, loopwagen, luikarm en een veer. De loopwagen geeft extra stabiliteit t.o.v. andere systemen. Standaard voorzien van aftimmerlatten en kunststof parket\/laminaatbeschermers. De trap ligt op het luik waardoor geen zwenkruimte benodigd is.<\/p>\n<p><strong>Opties<\/strong><\/p>\n<ul>\n<li>luik 76 mm\u00a0(U=0,92 W\/m2K)<\/li>\n<li>telescopische leuning<\/li>\n<li>traphek<\/li>\n<li>bovenluik<\/li>\n<li>plafondhoogtes tot 408 cm<\/li>\n<\/ul>\n<h6><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-707 alignleft\" src=\"http:\/\/www.twenta.nl\/\/wp-content\/uploads\/maatplan_schaartrap_V01-300x272.jpg\" alt=\"maatplan_schaartrap_V01\" width=\"300\" height=\"272\" srcset=\"https:\/\/www.twenta.nl\/wp-content\/uploads\/maatplan_schaartrap_V01-300x272.jpg 300w, https:\/\/www.twenta.nl\/wp-content\/uploads\/maatplan_schaartrap_V01-330x300.jpg 330w, https:\/\/www.twenta.nl\/wp-content\/uploads\/maatplan_schaartrap_V01.jpg 416w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <strong>Afmetingen<\/strong><\/h6>\n<p>A = grootte ruwe trapgat B = raveelbakhoogte C = plafondhoogte D = niet van toepassing E = grondmaat F = minimale zwenkruimte beneden<\/p>\n<table border=\"0\" width=\"325\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col span=\"5\" width=\"65\" \/><\/colgroup>\n<tbody>\n<tr>\n<td width=\"65\" height=\"15\">A<\/td>\n<td width=\"65\">B<\/td>\n<td width=\"65\">C<\/td>\n<td width=\"65\">D<\/td>\n<td width=\"65\">E<\/td>\n<\/tr>\n<tr>\n<td height=\"15\">70&#215;110\/120\/130\/140<\/td>\n<td>19,5<\/td>\n<td align=\"right\">240<\/td>\n<td>&#8211;<\/td>\n<td align=\"right\">135<\/td>\n<\/tr>\n<tr>\n<td height=\"15\">70&#215;110\/120\/130\/140<\/td>\n<td>19,5<\/td>\n<td align=\"right\">260<\/td>\n<td>&#8211;<\/td>\n<td align=\"right\">150<\/td>\n<\/tr>\n<tr>\n<td height=\"15\">70&#215;110\/120\/130\/140<\/td>\n<td>19,5<\/td>\n<td align=\"right\">280<\/td>\n<td>&#8211;<\/td>\n<td align=\"right\">165<\/td>\n<\/tr>\n<tr>\n<td height=\"15\">70&#215;110\/120\/130\/140<\/td>\n<td align=\"right\">19.5<\/td>\n<td align=\"right\">300<\/td>\n<td>&#8211;<\/td>\n<td align=\"right\">165<\/td>\n<\/tr>\n<tr>\n<td height=\"15\">70&#215;110\/120\/130\/140<\/td>\n<td align=\"right\">19.5<\/td>\n<td align=\"right\">320<\/td>\n<td>&#8211;<\/td>\n<td align=\"right\">180<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>DIN EN 14975 : 2010-12 k-waarde : 1,1\u00a0W\/m2K Maximale belasting : 175 kg Luchtdichtheidsklasse : klasse 4 Type 2400 is het summum van de vlieringtrappen, speciaal bij frequent gebruik en plafondhoogtes boven 280 cm. Vervaardigd uit zware gegoten aluminium profielen &hellip; <a href=\"https:\/\/www.twenta.nl\/be\/produkten-2\/bodentreppen-aluminium\/gegoten-aluminium-type-2400-d\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"parent":374,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-381","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"DIN EN 14975 : 2010-12 U-Wert : 1,1 W\/m2K Maximale Belastung : 175 kg Luftdichtheitsklasse : Klasse 4 Der Typ 2400 ist das Nonplusultra unter den Bodentreppen. Der Typ 2400 wird aus schweren, gegossenen Aluminiumprofilen hergestellt. Die polierten Stufen sind ganze 14 cm tief. Bei h\u00e4ufigem Gebrauch und Deckenh\u00f6hen \u00fcber 280 cm empfehlen wir den Typ 2400. Diese Treppe wird\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.twenta.nl\/be\/produkten-2\/bodentreppen-aluminium\/gegoten-aluminium-type-2400-d\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Twenta BV | bodentreppen, loftladders, vlieringtrappen, zoldertrappen, kniestockt\u00fcren\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Type 2400, gegoten aluminium schaartrap | Twenta BV\" \/>\n\t\t<meta property=\"og:description\" content=\"DIN EN 14975 : 2010-12 U-Wert : 1,1 W\/m2K Maximale Belastung : 175 kg Luftdichtheitsklasse : Klasse 4 Der Typ 2400 ist das Nonplusultra unter den Bodentreppen. Der Typ 2400 wird aus schweren, gegossenen Aluminiumprofilen hergestellt. Die polierten Stufen sind ganze 14 cm tief. Bei h\u00e4ufigem Gebrauch und Deckenh\u00f6hen \u00fcber 280 cm empfehlen wir den Typ 2400. Diese Treppe wird\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.twenta.nl\/be\/produkten-2\/bodentreppen-aluminium\/gegoten-aluminium-type-2400-d\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-06-03T10:23:03+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2015-07-19T10:07:06+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Type 2400, gegoten aluminium schaartrap | Twenta BV\" \/>\n\t\t<meta name=\"twitter:description\" content=\"DIN EN 14975 : 2010-12 U-Wert : 1,1 W\/m2K Maximale Belastung : 175 kg Luftdichtheitsklasse : Klasse 4 Der Typ 2400 ist das Nonplusultra unter den Bodentreppen. Der Typ 2400 wird aus schweren, gegossenen Aluminiumprofilen hergestellt. Die polierten Stufen sind ganze 14 cm tief. Bei h\u00e4ufigem Gebrauch und Deckenh\u00f6hen \u00fcber 280 cm empfehlen wir den Typ 2400. Diese Treppe wird\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/be\\\/produkten-2\\\/bodentreppen-aluminium\\\/gegoten-aluminium-type-2400-d\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/be#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.twenta.nl\\\/be\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/be\\\/produkten-2\\\/#listItem\",\"name\":\"Producten\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/be\\\/produkten-2\\\/#listItem\",\"position\":2,\"name\":\"Producten\",\"item\":\"https:\\\/\\\/www.twenta.nl\\\/be\\\/produkten-2\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/be\\\/produkten-2\\\/bodentreppen-aluminium\\\/#listItem\",\"name\":\"Aluminium vlieringtrappen\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/be#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/be\\\/produkten-2\\\/bodentreppen-aluminium\\\/#listItem\",\"position\":3,\"name\":\"Aluminium vlieringtrappen\",\"item\":\"https:\\\/\\\/www.twenta.nl\\\/be\\\/produkten-2\\\/bodentreppen-aluminium\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/be\\\/produkten-2\\\/bodentreppen-aluminium\\\/gegoten-aluminium-type-2400-d\\\/#listItem\",\"name\":\"Type 2400, gegoten aluminium schaartrap\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/be\\\/produkten-2\\\/#listItem\",\"name\":\"Producten\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/be\\\/produkten-2\\\/bodentreppen-aluminium\\\/gegoten-aluminium-type-2400-d\\\/#listItem\",\"position\":4,\"name\":\"Type 2400, gegoten aluminium schaartrap\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/be\\\/produkten-2\\\/bodentreppen-aluminium\\\/#listItem\",\"name\":\"Aluminium vlieringtrappen\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/be\\\/#person\",\"name\":\"Danny\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/be\\\/produkten-2\\\/bodentreppen-aluminium\\\/gegoten-aluminium-type-2400-d\\\/#webpage\",\"url\":\"https:\\\/\\\/www.twenta.nl\\\/be\\\/produkten-2\\\/bodentreppen-aluminium\\\/gegoten-aluminium-type-2400-d\\\/\",\"name\":\"Type 2400, gegoten aluminium schaartrap | Twenta BV\",\"description\":\"DIN EN 14975 : 2010-12 U-Wert : 1,1 W\\\/m2K Maximale Belastung : 175 kg Luftdichtheitsklasse : Klasse 4 Der Typ 2400 ist das Nonplusultra unter den Bodentreppen. Der Typ 2400 wird aus schweren, gegossenen Aluminiumprofilen hergestellt. Die polierten Stufen sind ganze 14 cm tief. Bei h\\u00e4ufigem Gebrauch und Deckenh\\u00f6hen \\u00fcber 280 cm empfehlen wir den Typ 2400. Diese Treppe wird\",\"inLanguage\":\"be-BE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/be\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/be\\\/produkten-2\\\/bodentreppen-aluminium\\\/gegoten-aluminium-type-2400-d\\\/#breadcrumblist\"},\"datePublished\":\"2012-06-03T12:23:03+02:00\",\"dateModified\":\"2015-07-19T12:07:06+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/be\\\/#website\",\"url\":\"https:\\\/\\\/www.twenta.nl\\\/be\\\/\",\"name\":\"Twenta BV\",\"description\":\"bodentreppen, loftladders, vlieringtrappen, zoldertrappen, kniestockt\\u00fcren\",\"inLanguage\":\"be-BE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.twenta.nl\\\/be\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Type 2400, gegoten aluminium schaartrap | Twenta BV","description":"DIN EN 14975 : 2010-12 U-Wert : 1,1 W\/m2K Maximale Belastung : 175 kg Luftdichtheitsklasse : Klasse 4 Der Typ 2400 ist das Nonplusultra unter den Bodentreppen. Der Typ 2400 wird aus schweren, gegossenen Aluminiumprofilen hergestellt. Die polierten Stufen sind ganze 14 cm tief. Bei h\u00e4ufigem Gebrauch und Deckenh\u00f6hen \u00fcber 280 cm empfehlen wir den Typ 2400. Diese Treppe wird","canonical_url":"https:\/\/www.twenta.nl\/be\/produkten-2\/bodentreppen-aluminium\/gegoten-aluminium-type-2400-d\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.twenta.nl\/be\/produkten-2\/bodentreppen-aluminium\/gegoten-aluminium-type-2400-d\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.twenta.nl\/be#listItem","position":1,"name":"Home","item":"https:\/\/www.twenta.nl\/be","nextItem":{"@type":"ListItem","@id":"https:\/\/www.twenta.nl\/be\/produkten-2\/#listItem","name":"Producten"}},{"@type":"ListItem","@id":"https:\/\/www.twenta.nl\/be\/produkten-2\/#listItem","position":2,"name":"Producten","item":"https:\/\/www.twenta.nl\/be\/produkten-2\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.twenta.nl\/be\/produkten-2\/bodentreppen-aluminium\/#listItem","name":"Aluminium vlieringtrappen"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.twenta.nl\/be#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.twenta.nl\/be\/produkten-2\/bodentreppen-aluminium\/#listItem","position":3,"name":"Aluminium vlieringtrappen","item":"https:\/\/www.twenta.nl\/be\/produkten-2\/bodentreppen-aluminium\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.twenta.nl\/be\/produkten-2\/bodentreppen-aluminium\/gegoten-aluminium-type-2400-d\/#listItem","name":"Type 2400, gegoten aluminium schaartrap"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.twenta.nl\/be\/produkten-2\/#listItem","name":"Producten"}},{"@type":"ListItem","@id":"https:\/\/www.twenta.nl\/be\/produkten-2\/bodentreppen-aluminium\/gegoten-aluminium-type-2400-d\/#listItem","position":4,"name":"Type 2400, gegoten aluminium schaartrap","previousItem":{"@type":"ListItem","@id":"https:\/\/www.twenta.nl\/be\/produkten-2\/bodentreppen-aluminium\/#listItem","name":"Aluminium vlieringtrappen"}}]},{"@type":"Person","@id":"https:\/\/www.twenta.nl\/be\/#person","name":"Danny"},{"@type":"WebPage","@id":"https:\/\/www.twenta.nl\/be\/produkten-2\/bodentreppen-aluminium\/gegoten-aluminium-type-2400-d\/#webpage","url":"https:\/\/www.twenta.nl\/be\/produkten-2\/bodentreppen-aluminium\/gegoten-aluminium-type-2400-d\/","name":"Type 2400, gegoten aluminium schaartrap | Twenta BV","description":"DIN EN 14975 : 2010-12 U-Wert : 1,1 W\/m2K Maximale Belastung : 175 kg Luftdichtheitsklasse : Klasse 4 Der Typ 2400 ist das Nonplusultra unter den Bodentreppen. Der Typ 2400 wird aus schweren, gegossenen Aluminiumprofilen hergestellt. Die polierten Stufen sind ganze 14 cm tief. Bei h\u00e4ufigem Gebrauch und Deckenh\u00f6hen \u00fcber 280 cm empfehlen wir den Typ 2400. Diese Treppe wird","inLanguage":"be-BE","isPartOf":{"@id":"https:\/\/www.twenta.nl\/be\/#website"},"breadcrumb":{"@id":"https:\/\/www.twenta.nl\/be\/produkten-2\/bodentreppen-aluminium\/gegoten-aluminium-type-2400-d\/#breadcrumblist"},"datePublished":"2012-06-03T12:23:03+02:00","dateModified":"2015-07-19T12:07:06+02:00"},{"@type":"WebSite","@id":"https:\/\/www.twenta.nl\/be\/#website","url":"https:\/\/www.twenta.nl\/be\/","name":"Twenta BV","description":"bodentreppen, loftladders, vlieringtrappen, zoldertrappen, kniestockt\u00fcren","inLanguage":"be-BE","publisher":{"@id":"https:\/\/www.twenta.nl\/be\/#person"}}]},"og:locale":"en_US","og:site_name":"Twenta BV | bodentreppen, loftladders, vlieringtrappen, zoldertrappen, kniestockt\u00fcren","og:type":"article","og:title":"Type 2400, gegoten aluminium schaartrap | Twenta BV","og:description":"DIN EN 14975 : 2010-12 U-Wert : 1,1 W\/m2K Maximale Belastung : 175 kg Luftdichtheitsklasse : Klasse 4 Der Typ 2400 ist das Nonplusultra unter den Bodentreppen. Der Typ 2400 wird aus schweren, gegossenen Aluminiumprofilen hergestellt. Die polierten Stufen sind ganze 14 cm tief. Bei h\u00e4ufigem Gebrauch und Deckenh\u00f6hen \u00fcber 280 cm empfehlen wir den Typ 2400. Diese Treppe wird","og:url":"https:\/\/www.twenta.nl\/be\/produkten-2\/bodentreppen-aluminium\/gegoten-aluminium-type-2400-d\/","article:published_time":"2012-06-03T10:23:03+00:00","article:modified_time":"2015-07-19T10:07:06+00:00","twitter:card":"summary","twitter:title":"Type 2400, gegoten aluminium schaartrap | Twenta BV","twitter:description":"DIN EN 14975 : 2010-12 U-Wert : 1,1 W\/m2K Maximale Belastung : 175 kg Luftdichtheitsklasse : Klasse 4 Der Typ 2400 ist das Nonplusultra unter den Bodentreppen. Der Typ 2400 wird aus schweren, gegossenen Aluminiumprofilen hergestellt. Die polierten Stufen sind ganze 14 cm tief. Bei h\u00e4ufigem Gebrauch und Deckenh\u00f6hen \u00fcber 280 cm empfehlen wir den Typ 2400. Diese Treppe wird"},"aioseo_meta_data":{"post_id":"381","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-04 15:53:34","updated":"2025-07-15 12:55:43","seo_analyzer_scan_date":null},"_links":{"self":[{"href":"https:\/\/www.twenta.nl\/be\/wp-json\/wp\/v2\/pages\/381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.twenta.nl\/be\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.twenta.nl\/be\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.twenta.nl\/be\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.twenta.nl\/be\/wp-json\/wp\/v2\/comments?post=381"}],"version-history":[{"count":25,"href":"https:\/\/www.twenta.nl\/be\/wp-json\/wp\/v2\/pages\/381\/revisions"}],"predecessor-version":[{"id":1786,"href":"https:\/\/www.twenta.nl\/be\/wp-json\/wp\/v2\/pages\/381\/revisions\/1786"}],"up":[{"embeddable":true,"href":"https:\/\/www.twenta.nl\/be\/wp-json\/wp\/v2\/pages\/374"}],"wp:attachment":[{"href":"https:\/\/www.twenta.nl\/be\/wp-json\/wp\/v2\/media?parent=381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}